{"id":826628,"date":"2026-06-23T13:55:07","date_gmt":"2026-06-23T13:55:07","guid":{"rendered":"https:\/\/www.ninjaone.com\/?p=826628"},"modified":"2026-06-23T13:57:09","modified_gmt":"2026-06-23T13:57:09","slug":"ripristina-le-app-predefinite-per-i-tipi-di-file-in-windows","status":"publish","type":"post","link":"https:\/\/www.ninjaone.com\/it\/blog\/ripristina-le-app-predefinite-per-i-tipi-di-file-in-windows\/","title":{"rendered":"Come reimpostare e ripristinare le app predefinite per i tipi di file in Windows 11"},"content":{"rendered":"<p>Windows gestisce ogni giorno un numero infinito di file, ma l&#8217;uso di applicazioni non adeguate pu\u00f2 compromettere la nostra produttivit\u00e0. Puoi risolvere facilmente i problemi relativi ai file, come i PDF, in qualsiasi browser, <strong>reimpostando le app predefinite per i vari tipi di file in Windows 11<\/strong>.<\/p>\n<p>L&#8217;utilizzo di impostazioni predefinite coerenti \u00e8 pratico, aumenta la produttivit\u00e0, garantisce il rispetto degli standard IT e semplifica la risoluzione dei problemi. In questa guida imparerai, passo dopo passo, come ripristinare le associazioni predefinite dei file in Windows 11.<\/p>\n<p>\ud83c\udfa5 Guarda il video tutorial \u2013 <a href=\"https:\/\/www.ninjaone.com\/videos\/windows\/how-to-reset-and-restore-default-apps-for-file-types-in-windows-11\/\">Come reimpostare e ripristinare le app predefinite per i tipi di file in Windows 11<\/a>.<\/p>\n<h2>Metodo 1: Reimposta tutte le app predefinite tramite Impostazioni<\/h2>\n<p>Ripristinare tutte le app predefinite in Windows 11 \u00e8 semplicissimo utilizzando il metodo delle Impostazioni.<\/p>\n<ol>\n<li><strong>Apri le impostazioni:<\/strong>\n<ul>\n<li>Premi <em>Win + I<\/em> per aprire le <strong>Impostazioni<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Vai alle app predefinite:<\/strong>\n<ul>\n<li>Accedi alla sezione <strong>App &gt; App predefinite<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Reimposta associazioni:<\/strong>\n<ul>\n<li>Scorri fino in fondo alla pagina, quindi fai clic su &#8220;<strong>Ripristina tutte le app predefinite<\/strong>&#8221; nella sezione &#8220;<strong>Impostazioni correlate<\/strong>&#8220;.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-487754\" src=\"https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-2.png\" alt=\"Opzione &quot;App predefinite&quot; per ripristinare tutte le app predefinite\" width=\"501\" height=\"389\" srcset=\"https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-2.png 501w, https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-2-300x233.png 300w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/p>\n<ol start=\"4\">\n<li><strong>Conferma l&#8217;azione:<\/strong><\/li>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Quando richiesto, fai clic su <strong>S\u00ec<\/strong>. Questa operazione ripristina immediatamente le impostazioni predefinite di Microsoft per tutti i tipi di file (ad esempio, PDF, immagini), come Edge, Foto o <a href=\"https:\/\/www.ninjaone.com\/it\/blog\/disinstallare-windows-media-player-legacy-app\/\">Media Player<\/a>.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<h2>Metodo 2: Ripristinare un tipo di file specifico tramite il Registro di sistema (file<strong>. reg<\/strong> )<\/h2>\n<p>Un file di Registro di sistema (<strong>. reg<\/strong>) pu\u00f2 essere utilizzato per selezionare tipi di file specifici in Windows 11.<\/p>\n<ol>\n<li><strong>Creare il file .reg:<\/strong><\/li>\n<li style=\"list-style-type: none;\">\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Apri <strong>Blocco note<\/strong> e incolla:<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 80px;\"><code>Windows Registry Editor Version 5.00<\/code><\/p>\n<p style=\"padding-left: 80px;\"><code>[HKEY_CURRENT_USER\\Software\\Microsoft\\Windows\\CurrentVersion\\Explorer\\FileExts\\<\/code><strong><code>. ext<\/code><\/strong><code>\\UserChoice]<\/code><\/p>\n<p style=\"padding-left: 80px;\"><code>\"ProgId\"=\"<\/code><strong><code>&lt;inserire qui l'applicazione&gt;<\/code><\/strong><code>\"<\/code><\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol style=\"list-style-type: lower-alpha;\" start=\"2\">\n<li>Sostituisci <strong>.ext<\/strong> con l&#8217;estensione del file che desideri reimpostare (ad es. .txt, .pdf) e inserisci il percorso corretto dell&#8217;eseguibile dell&#8217;applicazione o il ProgID in <strong>&lt;inserisci qui l\u2019applicazione&gt;<\/strong>, ad esempio <strong>Applications\\\\notepad.exe<\/strong> per Blocco note o <strong>MSEdgePDF<\/strong> per Microsoft Edge<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 80px;\"><strong><em>Esempio:<\/em><\/strong><\/p>\n<p style=\"padding-left: 80px;\"><code>Windows Registry Editor Version 5.00<\/code><\/p>\n<p style=\"padding-left: 80px;\"><code>[HKEY_CURRENT_USER\\Software\\Microsoft\\Windows\\CurrentVersion\\Explorer\\FileExts\\.pdf\\UserChoice]<\/code><\/p>\n<p style=\"padding-left: 80px;\"><code>\"ProgId\"=\"MSEdgePDF\"<\/code><\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol style=\"list-style-type: lower-alpha;\" start=\"3\">\n<li>Salva come <strong>Restore-&lt;Tipo di file&gt;-Default.reg <\/strong>(ad es., <em>Restore-<\/em><strong><em>MSEdgePDF<\/em><\/strong><em>-Default.reg<\/em>), quindi seleziona \u201c<em>Tutti i file<\/em>\u201d nella finestra di dialogo di salvataggio.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ol start=\"2\">\n<li><strong>Applica la correzione del Registro di sistema:<\/strong><\/li>\n<li style=\"list-style-type: none;\">\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Fai doppio clic sul file <strong>. reg<\/strong>, fai clic su <strong>S\u00ec<\/strong> per confermare, quindi riavvia <strong>Esplora file<\/strong> (tramite Gestione attivit\u00e0) oppure disconnettiti.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h2>Metodo 3: Pulizia del Registro di sistema per un tipo di file (ripristino manuale)<\/h2>\n<p>Per un controllo specifico sui singoli tipi di file, puoi reimpostare direttamente le associazioni modificando manualmente il Registro di sistema in Windows 11.<\/p>\n<p><strong><em>NOTA:<\/em><\/strong>\u00a0<em>Assicurati di eseguire un backup del Registro di sistema per proteggere il tuo sistema da modifiche accidentali. Per saperne di pi\u00f9, clicca qui: <\/em><a href=\"https:\/\/www.ninjaone.com\/it\/blog\/back-up-e-ripristino-del-registro-di-windows\/\"><em>Come eseguire il backup e il ripristino del Registro di sistema di Windows<\/em><\/a><em>.<\/em><\/p>\n<ol>\n<li><strong>Apri l&#8217;Editor del Registro di sistema:<\/strong><\/li>\n<li style=\"list-style-type: none;\">\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Premi <em>Win + R<\/em> per aprire la finestra di dialogo &#8220;<strong>Esegui<\/strong>&#8220;.<\/li>\n<li>Digita <em>regedit<\/em>, quindi premi <strong>Invio<\/strong> per aprire l&#8217;<strong>Editor del Registro di sistema <\/strong>(assicurati di disporre dei diritti di amministratore per poter apportare ulteriori modifiche al Registro di sistema).<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-487768\" src=\"https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-3.png\" alt=\"Esegui la finestra di dialogo per aprire l'Editor del Registro di sistema\" width=\"443\" height=\"254\" srcset=\"https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-3.png 443w, https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-3-300x172.png 300w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><\/p>\n<ol start=\"2\">\n<li><strong>Accedi alla voce &#8220;Estensione file&#8221;:<\/strong><\/li>\n<li style=\"list-style-type: none;\">\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Vai su:<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 80px;\"><strong>HKEY_CURRENT_USER\\Software\\Microsoft\\Windows\\CurrentVersion\\Explorer\\FileExts\\<\/strong><strong>. ext<\/strong><\/p>\n<p style=\"padding-left: 80px;\">\u26a0\ufe0f <strong><em>NOTA: <\/em><\/strong><em>Sostituisci <\/em><strong><em>. ext<\/em><\/strong><em> con l&#8217;estensione di cui hai bisogno (ad es., <\/em><strong><em>. mp3<\/em><\/strong><em>, <\/em><strong><em>. docx<\/em><\/strong><em>).<\/em><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-487778\" src=\"https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-4.png\" alt=\"Vai alla voce &quot;Estensione file&quot;\" width=\"524\" height=\"377\" srcset=\"https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-4.png 524w, https:\/\/www.ninjaone.com\/wp-content\/uploads\/2025\/07\/How-to-Reset-and-Restore-Default-Apps-for-File-Types-4-300x216.png 300w\" sizes=\"(max-width: 524px) 100vw, 524px\" \/><\/p>\n<ol start=\"3\">\n<li><strong>Elimina la sottochiave UserChoice:<\/strong>\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Fai clic con il tasto destro del mouse sulla <strong>cartella UserChoice <\/strong>(all&#8217;interno della chiave dell&#8217;estensione), quindi seleziona <strong>Elimina<\/strong>.<\/li>\n<li>Conferma l&#8217;operazione.<\/li>\n<\/ol>\n<\/li>\n<li><strong>Applica le modifiche:<\/strong>\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Riavvia Esplora file tramite Gestione attivit\u00e0 oppure esci dall&#8217;account, quindi accedi nuovamente. Windows utilizzer\u00e0 ora il proprio gestore predefinito per quel tipo di file.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h2>Ripristino delle app predefinite in Windows 11 per flussi di lavoro pi\u00f9 fluidi<\/h2>\n<p>Una configurazione errata dei tipi di file in Windows 11 pu\u00f2 trasformare semplici operazioni in veri e propri grattacapi, come ad esempio l&#8217;apertura di un foglio di calcolo nell&#8217;applicazione sbagliata. Il ripristino delle app predefinite per i tipi di file riporta tutto alla normalit\u00e0, sia che si tratti di correggere un\u2019estensione specifica o l\u2019intero sistema. L&#8217;app Impostazioni offre un ripristino rapido, mentre i file <strong>.reg<\/strong> e DISM consentono di applicare correzioni mirate o in blocco.<\/p>\n<p>Per ottenere risultati ottimali, ti consigliamo di seguire le procedure indicate in questa guida, verificare attentamente i ProgID e testare le modifiche prima di procedere alla distribuzione su larga scala. Padroneggiando questi metodi, potrai garantire flussi di lavoro fluidi e mantenere alta la produttivit\u00e0 degli utenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Windows gestisce ogni giorno un numero infinito di file, ma l&#8217;uso di applicazioni non adeguate pu\u00f2 compromettere la nostra produttivit\u00e0. Puoi risolvere facilmente i problemi relativi ai file, come i PDF, in qualsiasi browser, reimpostando le app predefinite per i vari tipi di file in Windows 11. L&#8217;utilizzo di impostazioni predefinite coerenti \u00e8 pratico, aumenta [&hellip;]<\/p>\n","protected":false},"author":220,"featured_media":488781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"categories":[4354],"tags":[],"class_list":["post-826628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-operazioni-it"],"acf":[],"modified_by":"Chiara Cavalletti","_links":{"self":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/posts\/826628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/users\/220"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/comments?post=826628"}],"version-history":[{"count":1,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/posts\/826628\/revisions"}],"predecessor-version":[{"id":826633,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/posts\/826628\/revisions\/826633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/media\/488781"}],"wp:attachment":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/media?parent=826628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/categories?post=826628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/tags?post=826628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}