{"id":353410,"date":"2024-08-16T15:05:55","date_gmt":"2024-08-16T15:05:55","guid":{"rendered":"https:\/\/www.ninjaone.com\/it-hub\/%content_hub_category%\/cos-e-la-golden-image\/"},"modified":"2024-10-13T14:24:11","modified_gmt":"2024-10-13T14:24:11","slug":"cos-e-la-golden-image","status":"publish","type":"content_hub","link":"https:\/\/www.ninjaone.com\/it\/it-hub\/accesso-remoto\/cos-e-la-golden-image\/","title":{"rendered":"Che cos&#8217;\u00e8 la Golden Image?"},"content":{"rendered":"<p>Una <strong>golden image<\/strong>, altrimenti nota come immagine clone, di base o master, \u00e8 il modello di una macchina virtuale, di un server o di un disco rigido. Una golden image \u00e8 una &#8220;istantanea&#8221; preconfigurata e perfettamente funzionante di un sistema informatico o di una configurazione software, lo standard &#8220;aureo&#8221; di ci\u00f2 che si sta cercando di replicare. <em>(L&#8217;etimologia del termine deriva dalla vecchia pratica di registrare i CD con una pellicola dorata, per far capire che i CD color oro sono la fonte originale dei dati<\/em>).<\/p>\n<p>Gli amministratori IT utilizzano le golden image per snellire e ottimizzare il processo di distribuzione (<em>o quando <\/em><a href=\"https:\/\/www.ninjaone.com\/blog\/zero-touch-device-provisioning\/\" target=\"_blank\" rel=\"noopener\"><em>si applica il provisioning zero-touch basato su USB<\/em><\/a>). Questo avviene perch\u00e9 le applicazioni mission-critical non dipendono pi\u00f9 dal dispositivo utilizzato, ma dal server o dalla rete stessa. Oltre a risparmiare tempo, soprattutto se si tratta di un&#8217;organizzazione di grandi dimensioni, si elimina anche la necessit\u00e0 di apportare modifiche ripetitive alla configurazione che potrebbero aumentare il rischio di <a href=\"https:\/\/www.ninjaone.com\/blog\/how-human-error-relates-to-cybersecurity-risks\/\" target=\"_blank\" rel=\"noopener\">errore umano<\/a>.<\/p>\n\n<h2>Cosa comprende una golden image?<\/h2>\n<p>Per creare una golden image, l&#8217;amministratore IT deve prima impostare l&#8217;ambiente informatico con le specifiche e le configurazioni esatte necessarie e poi catturare e salvare questa immagine per una futura replica. In genere, una golden image comprende:<\/p>\n<ul>\n<li>Un sistema operativo<\/li>\n<li>Software line-of-business<\/li>\n<\/ul>\n<p>La NIST Special Publication 800-53, &#8220;<a href=\"https:\/\/nvlpubs.nist.gov\/nistpubs\/SpecialPublications\/NIST.SP.800-53r5.pdf\" target=\"_blank\" rel=\"noopener\">Security and Privacy Controls for Information Systems and Organizations<\/a>&#8221; (al momento in cui scriviamo, attualmente in revisione 5) fa riferimento alle golden image come &#8220;configurazioni di base&#8221;, in cui:<\/p>\n<p><em>\u201cLe configurazioni di base servono come fondamento per le future creazioni, versioni o modifiche dei sistemi e comprendono le implementazioni dei controlli di sicurezza e della privacy, le procedure operative, le informazioni sui componenti del sistema, la topologia della rete e la collocazione logica dei componenti nell&#8217;architettura del sistema. <\/em><\/p>\n<p><em>Per mantenere le configurazioni di base \u00e8 necessario crearne di nuove, in quanto i sistemi organizzativi cambiano nel tempo. Le configurazioni di base dei sistemi riflettono l&#8217;attuale architettura aziendale,&#8221;<\/em><\/p>\n<p>\u00c8 opportuno notare che la golden image pu\u00f2 variare a seconda che si tratti di un&#8217;immagine disco spessa, sottile o ibrida.<\/p>\n<h3>Qual \u00e8 la differenza tra immagini spesse e immagini sottili?<\/h3>\n<div style=\"overflow-x: auto;\">\n<table class=\"we-are-the-best\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><strong>Immagini spesse<\/strong><\/td>\n<td style=\"text-align: center;\"><strong>Immagini sottili<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Un&#8217;immagine &#8220;tutto in uno&#8221; creata dagli amministratori IT. Una volta distribuite, tutte le applicazioni sono gi\u00e0 presenti e necessitano solo di piccole modifiche.<\/td>\n<td>\u00c8 pi\u00f9 basato sui processi, in cui l&#8217;immagine del disco viene distribuita e gli aggiornamenti, le applicazioni e le configurazioni fanno parte di una sequenza di attivit\u00e0 o di un criterio di gruppo.<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li>Include app, driver hardware e personalizzazioni.<\/li>\n<li>Hanno dimensioni di file maggiori.<\/li>\n<li>Sono meno scalabili in ambienti diversi.<\/li>\n<\/ul>\n<\/td>\n<td>\n<ul>\n<li>In genere, include solo i file del sistema operativo.<\/li>\n<li>Pi\u00f9 veloce da implementare.<\/li>\n<li>Deve essere configurato separatamente sulle macchine.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>Le immagini ibride sono una via di mezzo tra le due. \u00c8 fondamentale stabilire che tipo di immagine desideri che sia la tua golden image. Sebbene sia facile pensare che le immagini spesse siano migliori, \u00e8 necessario considerare anche i tuoi sistemi esistenti e le altre risorse.<\/p>\n<h2>Vantaggi dell&#8217;utilizzo di una golden image<\/h2>\n<p>Le golden image sono essenziali per il <a href=\"https:\/\/www.ninjaone.com\/rmm\/device-provisioning\/\" target=\"_blank\" rel=\"noopener\">provisioning dei dispositivi<\/a> e per qualsiasi processo che garantisca la sicurezza e la conformit\u00e0 degli endpoint.<\/p>\n<ul>\n<li><strong>Risparmia tempo. <\/strong>Le golden image possono contribuire all&#8217;<a href=\"https:\/\/www.ninjaone.com\/it-hub\/endpoint-security\/what-is-operational-efficiency\/\" target=\"_blank\" rel=\"noopener\">efficienza operativa<\/a> complessiva, poich\u00e9 non \u00e8 necessario configurare i dispositivi singolarmente. Ad esempio, le golden image possono aiutarti a introdurre un nuovo software senza compromettere la coerenza o le prestazioni del tuo parco macchine. <em>(Consulta la nostra guida sui <\/em><a href=\"https:\/\/www.ninjaone.com\/it\/blog\/migliori-strumenti-di-distribuzione-del-software-da-remoto\/\" target=\"_blank\" rel=\"noopener\"><em>10 migliori strumenti di distribuzione del software nel 2024<\/em><\/a><em> per ulteriori indicazioni<\/em>).<\/li>\n<li><strong>Assicura la coerenza. <\/strong>Una golden image riduce significativamente il rischio di incongruenze nel tuo parco dispositivi. L&#8217;immagine master garantisce che tutti i cloni futuri siano uguali. Si tratta di un punto che vale la pena considerare, poich\u00e9 l&#8217;<a href=\"https:\/\/connect.comptia.org\/content\/research\/it-industry-trends-analysis\" target=\"_blank\" rel=\"noopener\">ultimo IT Industry Outlook 2024<\/a> di CompTIA suggerisce che la coerenza \u00e8 (e sar\u00e0) fondamentale per qualsiasi <a href=\"https:\/\/www.ninjaone.com\/it-hub\/it-service-management\/what-is-a-governance-plan\/\" target=\"_blank\" rel=\"noopener\">piano di governance<\/a> dei dati per la cybersecurity, adesso e in futuro.<\/li>\n<li><strong>Riduce al minimo il bloatware.<\/strong> Le golden image rimuovono il bloatware che pu\u00f2 influire sulle prestazioni del dispositivo. Tuttavia, tieni presente che ci\u00f2 dipende anche da come \u00e8 stata realizzata la golden image. Un&#8217;immagine mal realizzata potrebbe non fornire il massimo beneficio alla tua organizzazione. <em>(Abbiamo realizzato un&#8217;altra guida su <\/em><a href=\"https:\/\/www.ninjaone.com\/blog\/how-to-find-remove-bloatware-from-windows-11\/\" target=\"_blank\" rel=\"noopener\"><em>come trovare e rimuovere il bloatware da Windows 11<\/em><\/a><em> qui<\/em>).<\/li>\n<\/ul>\n<h2>Best practice per la golden image<\/h2>\n<ul>\n<li><strong>Applica patch al tuo sistema operativo.<\/strong> Si consiglia vivamente di applicare patch al tuo sistema operativo prima di acquisire e distribuire la golden image. In questo modo si riducono le <a href=\"https:\/\/www.ninjaone.com\/it-hub\/endpoint-security\/what-is-security-vulnerability\/\" target=\"_blank\" rel=\"noopener\">vulnerabilit\u00e0 di sicurezza<\/a> dei tuoi dispositivi. Collabora con un fornitore come NinjaOne per una gestione automatizzata e efficace delle patch.<\/li>\n<\/ul>\n\n<ul>\n<li><strong>Utilizza macchine virtuali. <\/strong>Se possibile, utilizza una macchina virtuale per creare la tua golden image. Ci\u00f2 consente di risparmiare spazio fisico ed eventuali costi di software. Le macchine virtuali sono anche pi\u00f9 facili da scalare, il che le rende utili per gli <a href=\"https:\/\/www.ninjaone.com\/it\/cos-e-un-msp\" target=\"_blank\" rel=\"noopener\">MSP<\/a>, gli <a href=\"https:\/\/www.ninjaone.com\/blog\/what-is-a-managed-security-service-provider\/\" target=\"_blank\" rel=\"noopener\">MSSP<\/a> e le aziende IT in espansione.<\/li>\n<li><strong>Disattiva il software antivirus (quando crei l&#8217;immagine).<\/strong> In generale, durante la creazione e la distribuzione della golden image, disabilita qualsiasi antivirus o altra applicazione di terze parti. In questo modo si impedisce al nuovo dispositivo di identificare erroneamente la nuova immagine come malware e di adottare varie misure di sicurezza contro di te. \u00c8 sempre possibile installare il software antivirus dopo la creazione della golden image.<\/li>\n<li><strong>Testa la tua golden image. <\/strong>Crea ambienti di test autonomi per la tua golden image, soprattutto se \u00e8 la prima volta che ne realizzi una. In questo modo si garantisce che l&#8217;immagine master funzioni come dovrebbe nel processo di distribuzione previsto.<\/li>\n<li><strong>Mantieni le tue immagini aggiornate. <\/strong>La tua golden image \u00e8 utile solo quanto l&#8217;istantanea del tempo in cui \u00e8 stata creata. Si consiglia vivamente di mantenere aggiornati i sistemi operativi (e, di conseguenza, la libreria di immagini) per semplificare il processo di distribuzione e provisioning.<\/li>\n<\/ul>\n<h2>NinjaOne e golden image<\/h2>\n<p>NinjaOne non crea golden image, ma aiuta a utilizzarle correttamente nel processo di provisioning dei dispositivi. Oltre 17.000 clienti in tutto il mondo si affidano a NinjaOne per il provisioning dei dispositivi per la sua forte funzionalit\u00e0 di automazione, l&#8217;efficiente distribuzione del software e le sue capacit\u00e0 di risparmio di tempo.<\/p>\n<p>Il software di gestione IT di NinjaOne non prevede impegni vincolanti e non ha costi nascosti. Se sei pronto, richiedi un <a href=\"https:\/\/www.ninjaone.com\/it\/prezzi-per-dispositivo\/\" target=\"_blank\" rel=\"noopener\">preventivo gratuito<\/a>, iscriviti a una <a href=\"https:\/\/www.ninjaone.com\/it\/prova-gratuita\/\" target=\"_blank\" rel=\"noopener\">prova gratuita<\/a> di 14 giorni o <a href=\"https:\/\/www.ninjaone.com\/it\/gestione-degli-endpoint-demo-gratuita\/\" target=\"_blank\" rel=\"noopener\">guarda una demo<\/a>.<\/p>\n","protected":false},"author":152,"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_lmt_disableupdate":"","_lmt_disable":""},"hub_categories":[4191],"class_list":["post-353410","content_hub","type-content_hub","status-publish","hentry","content_hub_category-accesso-remoto"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/content_hub\/353410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/content_hub"}],"about":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/types\/content_hub"}],"author":[{"embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/users\/152"}],"wp:attachment":[{"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/media?parent=353410"}],"wp:term":[{"taxonomy":"content_hub_category","embeddable":true,"href":"https:\/\/www.ninjaone.com\/it\/wp-json\/wp\/v2\/hub_categories?post=353410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}