{"id":748537,"date":"2026-02-18T19:00:53","date_gmt":"2026-02-18T19:00:53","guid":{"rendered":"https:\/\/www.ninjaone.com\/docs\/integraciones-y-aplicaciones-de-terceros\/antivirus\/sentinelone\/solucion-de-problemas-de-sentinelone-componente-ninjaone-detectado-como-amenaza\/"},"modified":"2026-06-22T02:26:10","modified_gmt":"2026-06-22T02:26:10","slug":"solucion-de-problemas-de-sentinelone-componente-ninjaone-detectado-como-amenaza","status":"publish","type":"pseudo_docs","link":"https:\/\/www.ninjaone.com\/es\/docs\/integraciones-y-aplicaciones-de-terceros\/antivirus\/sentinelone\/solucion-de-problemas-de-sentinelone-componente-ninjaone-detectado-como-amenaza\/","title":{"rendered":"Soluci\u00f3n de problemas de SentinelOne: Componente NinjaOne detectado como amenaza"},"content":{"rendered":"","protected":false},"author":254,"featured_media":0,"parent":550171,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_lmt_disableupdate":"","_lmt_disable":""},"class_list":["post-748537","pseudo_docs","type-pseudo_docs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ninjaone.com\/es\/wp-json\/wp\/v2\/pseudo_docs\/748537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ninjaone.com\/es\/wp-json\/wp\/v2\/pseudo_docs"}],"about":[{"href":"https:\/\/www.ninjaone.com\/es\/wp-json\/wp\/v2\/types\/pseudo_docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.ninjaone.com\/es\/wp-json\/wp\/v2\/users\/254"}],"up":[{"embeddable":true,"href":"https:\/\/www.ninjaone.com\/es\/wp-json\/wp\/v2\/pseudo_docs\/550171"}],"wp:attachment":[{"href":"https:\/\/www.ninjaone.com\/es\/wp-json\/wp\/v2\/media?parent=748537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}